{"id":2102,"date":"2023-11-23T16:20:43","date_gmt":"2023-11-23T16:20:43","guid":{"rendered":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/?page_id=2102"},"modified":"2025-02-28T14:58:49","modified_gmt":"2025-02-28T14:58:49","slug":"report","status":"publish","type":"page","link":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/report\/","title":{"rendered":"Report"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-generic-page.php","meta":[],"class_list":["post-2102","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/pages\/2102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/comments?post=2102"}],"version-history":[{"count":15,"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/pages\/2102\/revisions"}],"predecessor-version":[{"id":2628,"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/pages\/2102\/revisions\/2628"}],"wp:attachment":[{"href":"https:\/\/south-ox-and-vale-landscape-evidence-base.co.uk\/Landscape-Character-Assessment\/wp-json\/wp\/v2\/media?parent=2102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}